{"id":15752,"date":"2015-07-03T12:44:40","date_gmt":"2015-07-03T12:44:40","guid":{"rendered":"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg"},"modified":"2015-07-03T12:44:40","modified_gmt":"2015-07-03T12:44:40","slug":"festanglo057","status":"inherit","type":"attachment","link":"https:\/\/www.colegioangloavare.com.br\/site\/festanglo057\/","title":{"rendered":"festanglo057"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"cybocfi_hide_featured_image":""},"class_list":["post-15752","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>festanglo057 - ANGLO AVAR\u00c9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"festanglo057 - ANGLO AVAR\u00c9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg\" \/>\n<meta property=\"og:site_name\" content=\"ANGLO AVAR\u00c9\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2272\" \/>\n\t<meta property=\"og:image:height\" content=\"1704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/festanglo057.jpg\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/festanglo057.jpg\",\"name\":\"festanglo057 - ANGLO AVAR\u00c9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#website\"},\"datePublished\":\"2015-07-03T12:44:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/festanglo057.jpg#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/festanglo057.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/festanglo057.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"festanglo057\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/\",\"name\":\"ANGLO AVAR\u00c9\",\"description\":\"Para os melhores professores, o melhor conte\u00fado. No Anglo, tudo come\u00e7a na sala de aula.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"festanglo057 - ANGLO AVAR\u00c9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg","og_locale":"pt_BR","og_type":"article","og_title":"festanglo057 - ANGLO AVAR\u00c9","og_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg","og_site_name":"ANGLO AVAR\u00c9","og_image":[{"width":2272,"height":1704,"url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg","url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg","name":"festanglo057 - ANGLO AVAR\u00c9","isPartOf":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/#website"},"datePublished":"2015-07-03T12:44:40+00:00","breadcrumb":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.colegioangloavare.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"festanglo057"}]},{"@type":"WebSite","@id":"https:\/\/www.colegioangloavare.com.br\/site\/#website","url":"https:\/\/www.colegioangloavare.com.br\/site\/","name":"ANGLO AVAR\u00c9","description":"Para os melhores professores, o melhor conte\u00fado. No Anglo, tudo come\u00e7a na sala de aula.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colegioangloavare.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057-300x225.jpg 300w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057-1024x768.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2272,"height":1704,"file":"2015\/07\/festanglo057.jpg","sizes":{"thumbnail":{"file":"festanglo057-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057-150x150.jpg"},"medium":{"file":"festanglo057-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057-300x225.jpg"},"large":{"file":"festanglo057-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057-1024x768.jpg"},"graphene_slider":{"file":"festanglo057-640x350.jpg","width":640,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057-640x350.jpg"},"post-thumbnail":{"file":"festanglo057-960x198.jpg","width":960,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057-960x198.jpg"},"full":{"file":"festanglo057.jpg","width":2272,"height":1704,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg"}},"image_meta":{"aperture":3.5,"credit":"","camera":"COOLPIX S9300","caption":"","created_timestamp":1435423111,"copyright":"","focal_length":"4.5","iso":"400","shutter_speed":"0.04","title":"","orientation":1}},"post":null,"source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo057.jpg","filename":"festanglo057.jpg","filesize":758152,"_links":{"self":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/media\/15752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/comments?post=15752"}]}}