{"id":15977,"date":"2015-07-03T13:45:05","date_gmt":"2015-07-03T13:45:05","guid":{"rendered":"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg"},"modified":"2015-07-03T13:45:05","modified_gmt":"2015-07-03T13:45:05","slug":"festanglo294","status":"inherit","type":"attachment","link":"https:\/\/www.colegioangloavare.com.br\/site\/festanglo294\/","title":{"rendered":"festanglo294"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"cybocfi_hide_featured_image":""},"class_list":["post-15977","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>festanglo294 - ANGLO AVAR\u00c9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"festanglo294 - ANGLO AVAR\u00c9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg\" \/>\n<meta property=\"og:site_name\" content=\"ANGLO AVAR\u00c9\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/festanglo294.jpg\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/festanglo294.jpg\",\"name\":\"festanglo294 - ANGLO AVAR\u00c9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#website\"},\"datePublished\":\"2015-07-03T13:45:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/festanglo294.jpg#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/festanglo294.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/festanglo294.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"festanglo294\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/\",\"name\":\"ANGLO AVAR\u00c9\",\"description\":\"Para os melhores professores, o melhor conte\u00fado. No Anglo, tudo come\u00e7a na sala de aula.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"festanglo294 - ANGLO AVAR\u00c9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg","og_locale":"pt_BR","og_type":"article","og_title":"festanglo294 - ANGLO AVAR\u00c9","og_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg","og_site_name":"ANGLO AVAR\u00c9","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg","url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg","name":"festanglo294 - ANGLO AVAR\u00c9","isPartOf":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/#website"},"datePublished":"2015-07-03T13:45:05+00:00","breadcrumb":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.colegioangloavare.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"festanglo294"}]},{"@type":"WebSite","@id":"https:\/\/www.colegioangloavare.com.br\/site\/#website","url":"https:\/\/www.colegioangloavare.com.br\/site\/","name":"ANGLO AVAR\u00c9","description":"Para os melhores professores, o melhor conte\u00fado. No Anglo, tudo come\u00e7a na sala de aula.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colegioangloavare.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294-300x169.jpg 300w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294-1024x576.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1440,"file":"2015\/07\/festanglo294.jpg","sizes":{"thumbnail":{"file":"festanglo294-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294-150x150.jpg"},"medium":{"file":"festanglo294-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294-300x169.jpg"},"large":{"file":"festanglo294-1024x576.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294-1024x576.jpg"},"graphene_slider":{"file":"festanglo294-640x350.jpg","width":640,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294-640x350.jpg"},"post-thumbnail":{"file":"festanglo294-960x198.jpg","width":960,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294-960x198.jpg"},"full":{"file":"festanglo294.jpg","width":2560,"height":1440,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg"}},"image_meta":{"aperture":2.2000000000000002,"credit":"","camera":"MotoE2(4G-LTE)","caption":"","created_timestamp":1435417507,"copyright":"","focal_length":"2.471","iso":"80","shutter_speed":"0.02872","title":"","orientation":0}},"post":null,"source_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/07\/festanglo294.jpg","_links":{"self":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/media\/15977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/comments?post=15977"}]}}