{"id":16523,"date":"2015-10-21T17:15:47","date_gmt":"2015-10-21T17:15:47","guid":{"rendered":"http:\/\/www.colegioangloavare.com.br\/site\/?p=16523"},"modified":"2015-10-21T17:22:23","modified_gmt":"2015-10-21T17:22:23","slug":"horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio","status":"publish","type":"post","link":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/","title":{"rendered":"Hor\u00e1rio de Recup. Semestral &#8211; 2\u00ba Semestre 2015 &#8211; 1\u00baA\/B\/C Ens. M\u00e9dio"},"content":{"rendered":"<p><strong>HOR\u00c1RIO DE RECUPERA\u00c7\u00c3O SEMESTRAL- 2\u00ba SEMESTRE-2015<\/strong><\/p>\n<p><strong>1\u00ba A\/B\/C- ENSINO M\u00c9DIO<\/strong><\/p>\n<p>&nbsp;<\/p>\n<table style=\"background-color: #adedc4;\">\n<tbody>\n<tr style=\"background-color: #579e88;\">\n<td width=\"66\"><strong>1\u00ba anos<\/strong><\/td>\n<td width=\"130\"><strong>01\/12<\/strong><\/p>\n<p><strong>3\u00aaf.<\/strong><\/td>\n<td width=\"130\"><strong>02\/12<\/strong><\/p>\n<p><strong>4\u00aaf.<\/strong><\/td>\n<td width=\"132\"><strong>03\/12<\/strong><\/p>\n<p><strong>5\u00aaf.<\/strong><\/td>\n<td width=\"117\"><strong>04\/12<\/strong><\/p>\n<p><strong>6\u00aaf.<\/strong><\/td>\n<td width=\"138\"><strong>07\/12<\/strong><\/p>\n<p><strong>2\u00aaf.<\/strong><\/td>\n<td width=\"119\"><strong>08\/12<\/strong><\/p>\n<p><strong>3\u00aaf.<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"66\">7:10<\/td>\n<td width=\"130\">Gram\u00e1tica<\/p>\n<p>Aula<\/td>\n<td width=\"130\">F\u00edsica-Aula<\/td>\n<td width=\"132\">Qu\u00edmica-aula<\/td>\n<td width=\"117\">Qu\u00edmica-aula<\/td>\n<td width=\"138\"><\/td>\n<td width=\"119\">Reda\u00e7\u00e3o -Prova<\/td>\n<\/tr>\n<tr style=\"background-color: #adedc4;\">\n<td width=\"66\">8:00<\/td>\n<td width=\"130\"><\/td>\n<td width=\"130\">F\u00edsica-Prova<\/td>\n<td width=\"132\">Qu\u00edmica-aula<\/td>\n<td width=\"117\">Qu\u00edmica-Prova<\/td>\n<td width=\"138\"><\/td>\n<td width=\"119\">Hist\u00f3ria Da Arte<\/p>\n<p>Prova<\/td>\n<\/tr>\n<tr>\n<td width=\"66\">8:50<\/td>\n<td width=\"130\">F\u00edsica-Aula<\/td>\n<td width=\"130\">Biologia<\/p>\n<p>Gabriel-Aula<\/td>\n<td width=\"132\">Matem\u00e1tica<\/p>\n<p>Prova-Geom.<\/td>\n<td width=\"117\">Sociologia-Prova<\/td>\n<td width=\"138\">Geografia-Aula<\/td>\n<td width=\"119\">Biologia-Patricia-Aula<\/td>\n<\/tr>\n<tr style=\"background-color: #adedc4;\">\n<td width=\"66\">10:00<\/td>\n<td width=\"130\">F\u00edsica-Aula<\/td>\n<td width=\"130\">Matem\u00e1tica<\/p>\n<p>Aula-Geom.<\/td>\n<td width=\"132\">Gram\u00e1tica-Prova<\/p>\n<p>&nbsp;<\/td>\n<td width=\"117\">Filosofia-Prova<\/td>\n<td width=\"138\">Geografia-Prova<\/td>\n<td width=\"119\">Biologia-Patricia-Prova<\/td>\n<\/tr>\n<tr>\n<td width=\"66\">10:50<\/td>\n<td width=\"130\">Ingl\u00eas-Aula<\/td>\n<td width=\"130\">Literatura-Aula<\/td>\n<td width=\"132\">Biologia<\/p>\n<p>Gabriel-Prova<\/td>\n<td width=\"117\">Hist\u00f3ria-Aula<\/td>\n<td width=\"138\">Matem\u00e1tica<\/p>\n<p>Aula-\u00c1lgebra<\/td>\n<td width=\"119\"><\/td>\n<\/tr>\n<tr style=\"background-color: #adedc4;\">\n<td width=\"66\">11:40<\/td>\n<td width=\"130\">Ingl\u00eas-Prova<\/td>\n<td width=\"130\">Literatura-Prova<\/td>\n<td width=\"132\"><\/td>\n<td width=\"117\">Hist\u00f3ria-Prova<\/td>\n<td width=\"138\">Matem\u00e1tica<\/p>\n<p>Prova-\u00c1lgebra<\/td>\n<td width=\"119\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>HOR\u00c1RIO DE RECUPERA\u00c7\u00c3O SEMESTRAL- 2\u00ba SEMESTRE-2015 1\u00ba A\/B\/C- ENSINO M\u00c9DIO &nbsp; 1\u00ba anos 01\/12 3\u00aaf. 02\/12 4\u00aaf. 03\/12 5\u00aaf. 04\/12 6\u00aaf. 07\/12 2\u00aaf. 08\/12 3\u00aaf. 7:10 Gram\u00e1tica Aula F\u00edsica-Aula Qu\u00edmica-aula Qu\u00edmica-aula Reda\u00e7\u00e3o<a class=\"moretag\" href=\"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":16525,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[41,3,6],"tags":[],"class_list":["post-16523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-41","category-arquivo","category-avisos-e-comunicados"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\/B\/C Ens. M\u00e9dio - ANGLO AVAR\u00c9<\/title>\n<meta name=\"description\" content=\"Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\/B\/C Ens. M\u00e9dio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\/B\/C Ens. M\u00e9dio - ANGLO AVAR\u00c9\" \/>\n<meta property=\"og:description\" content=\"Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\/B\/C Ens. M\u00e9dio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/\" \/>\n<meta property=\"og:site_name\" content=\"ANGLO AVAR\u00c9\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-21T17:15:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-10-21T17:22:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/10\/Hor\u00e1rio-Recup-Sem-1anos-2015.png\" \/>\n\t<meta property=\"og:image:width\" content=\"629\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"FREA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FREA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/\"},\"author\":{\"name\":\"FREA\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#\\\/schema\\\/person\\\/e93891dc9c89020ea5a481646d06cd32\"},\"headline\":\"Hor\u00e1rio de Recup. Semestral &#8211; 2\u00ba Semestre 2015 &#8211; 1\u00baA\\\/B\\\/C Ens. M\u00e9dio\",\"datePublished\":\"2015-10-21T17:15:47+00:00\",\"dateModified\":\"2015-10-21T17:22:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/\"},\"wordCount\":99,\"image\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Hor\u00e1rio-Recup-Sem-1anos-2015.png\",\"articleSection\":[\"2015\",\"Arquivo\",\"Avisos e Comunicados\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/\",\"name\":\"Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\\\/B\\\/C Ens. M\u00e9dio - ANGLO AVAR\u00c9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Hor\u00e1rio-Recup-Sem-1anos-2015.png\",\"datePublished\":\"2015-10-21T17:15:47+00:00\",\"dateModified\":\"2015-10-21T17:22:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#\\\/schema\\\/person\\\/e93891dc9c89020ea5a481646d06cd32\"},\"description\":\"Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\\\/B\\\/C Ens. M\u00e9dio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Hor\u00e1rio-Recup-Sem-1anos-2015.png\",\"contentUrl\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Hor\u00e1rio-Recup-Sem-1anos-2015.png\",\"width\":629,\"height\":426},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hor\u00e1rio de Recup. Semestral &#8211; 2\u00ba Semestre 2015 &#8211; 1\u00baA\\\/B\\\/C Ens. M\u00e9dio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/\",\"name\":\"ANGLO AVAR\u00c9\",\"description\":\"Para os melhores professores, o melhor conte\u00fado. No Anglo, tudo come\u00e7a na sala de aula.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#\\\/schema\\\/person\\\/e93891dc9c89020ea5a481646d06cd32\",\"name\":\"FREA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g\",\"caption\":\"FREA\"},\"description\":\"Departamento de Inform\u00e1tica na FUNDA\u00c7\u00c3O REGIONAL EDUCACIONAL DE AVAR\u00c9\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/author\\\/administrador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\/B\/C Ens. M\u00e9dio - ANGLO AVAR\u00c9","description":"Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\/B\/C Ens. M\u00e9dio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/","og_locale":"pt_BR","og_type":"article","og_title":"Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\/B\/C Ens. M\u00e9dio - ANGLO AVAR\u00c9","og_description":"Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\/B\/C Ens. M\u00e9dio","og_url":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/","og_site_name":"ANGLO AVAR\u00c9","article_published_time":"2015-10-21T17:15:47+00:00","article_modified_time":"2015-10-21T17:22:23+00:00","og_image":[{"width":629,"height":426,"url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/10\/Hor\u00e1rio-Recup-Sem-1anos-2015.png","type":"image\/png"}],"author":"FREA","twitter_misc":{"Escrito por":"FREA"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/#article","isPartOf":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/"},"author":{"name":"FREA","@id":"https:\/\/www.colegioangloavare.com.br\/site\/#\/schema\/person\/e93891dc9c89020ea5a481646d06cd32"},"headline":"Hor\u00e1rio de Recup. Semestral &#8211; 2\u00ba Semestre 2015 &#8211; 1\u00baA\/B\/C Ens. M\u00e9dio","datePublished":"2015-10-21T17:15:47+00:00","dateModified":"2015-10-21T17:22:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/"},"wordCount":99,"image":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/10\/Hor\u00e1rio-Recup-Sem-1anos-2015.png","articleSection":["2015","Arquivo","Avisos e Comunicados"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/","url":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/","name":"Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\/B\/C Ens. M\u00e9dio - ANGLO AVAR\u00c9","isPartOf":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/#primaryimage"},"image":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/10\/Hor\u00e1rio-Recup-Sem-1anos-2015.png","datePublished":"2015-10-21T17:15:47+00:00","dateModified":"2015-10-21T17:22:23+00:00","author":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/#\/schema\/person\/e93891dc9c89020ea5a481646d06cd32"},"description":"Hor\u00e1rio de Recup. Semestral - 2\u00ba Semestre 2015 - 1\u00baA\/B\/C Ens. M\u00e9dio","breadcrumb":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/#primaryimage","url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/10\/Hor\u00e1rio-Recup-Sem-1anos-2015.png","contentUrl":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/10\/Hor\u00e1rio-Recup-Sem-1anos-2015.png","width":629,"height":426},{"@type":"BreadcrumbList","@id":"https:\/\/www.colegioangloavare.com.br\/site\/horario-de-recup-semestral-2o-semestre-2015-1oabc-ens-medio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.colegioangloavare.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Hor\u00e1rio de Recup. Semestral &#8211; 2\u00ba Semestre 2015 &#8211; 1\u00baA\/B\/C Ens. M\u00e9dio"}]},{"@type":"WebSite","@id":"https:\/\/www.colegioangloavare.com.br\/site\/#website","url":"https:\/\/www.colegioangloavare.com.br\/site\/","name":"ANGLO AVAR\u00c9","description":"Para os melhores professores, o melhor conte\u00fado. No Anglo, tudo come\u00e7a na sala de aula.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colegioangloavare.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.colegioangloavare.com.br\/site\/#\/schema\/person\/e93891dc9c89020ea5a481646d06cd32","name":"FREA","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g","caption":"FREA"},"description":"Departamento de Inform\u00e1tica na FUNDA\u00c7\u00c3O REGIONAL EDUCACIONAL DE AVAR\u00c9","url":"https:\/\/www.colegioangloavare.com.br\/site\/author\/administrador\/"}]}},"jetpack_featured_media_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2015\/10\/Hor\u00e1rio-Recup-Sem-1anos-2015.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts\/16523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/comments?post=16523"}],"version-history":[{"count":2,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts\/16523\/revisions"}],"predecessor-version":[{"id":16526,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts\/16523\/revisions\/16526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/media\/16525"}],"wp:attachment":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/media?parent=16523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/categories?post=16523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/tags?post=16523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}