{"id":17270,"date":"2016-03-17T20:20:53","date_gmt":"2016-03-17T20:20:53","guid":{"rendered":"http:\/\/www.colegioangloavare.com.br\/site\/?p=17270"},"modified":"2016-03-17T20:21:18","modified_gmt":"2016-03-17T20:21:18","slug":"torneio-de-queimada-dos-5os-anos","status":"publish","type":"post","link":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/","title":{"rendered":"TORNEIO DE QUEIMADA DOS 5\u00bas ANOS"},"content":{"rendered":"<p>No dia 15 de mar\u00e7o foi realizado o Torneio de Queimada dos 5\u00bas Anos, do Col\u00e9gio Universit\u00e1rio de Avar\u00e9. Seis equipes participaram das disputas, sendo feitas pelo sistema de eliminat\u00f3ria simples, com jogos de cinco minutos. A equipe Campe\u00e3 foi a equipe &#8220;Pinheiros&#8221;, do 5\u00ba Ano-A. O professor Helio C. Hiray, Coordenador de Esportes do col\u00e9gio, aproveita a oportunidade, para agradecer a todas as equipes participantes e parabenizar pelo bom desempenho e disciplina.<\/p>\n<p><a href=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001.jpg\" rel=\"attachment wp-att-17271\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-17271\" src=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001.jpg\" alt=\"Torneio_de_queimada_5_anos_2016_00001\" width=\"800\" height=\"450\" srcset=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001.jpg 800w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001-300x169.jpg 300w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 15 de mar\u00e7o foi realizado o Torneio de Queimada dos 5\u00bas Anos, do Col\u00e9gio Universit\u00e1rio de Avar\u00e9. Seis equipes participaram das disputas, sendo feitas pelo sistema de eliminat\u00f3ria simples, com<a class=\"moretag\" href=\"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":17271,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[43,3,4],"tags":[],"class_list":["post-17270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-43","category-arquivo","category-esportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TORNEIO DE QUEIMADA DOS 5\u00bas ANOS - ANGLO AVAR\u00c9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TORNEIO DE QUEIMADA DOS 5\u00bas ANOS - ANGLO AVAR\u00c9\" \/>\n<meta property=\"og:description\" content=\"No dia 15 de mar\u00e7o foi realizado o Torneio de Queimada dos 5\u00bas Anos, do Col\u00e9gio Universit\u00e1rio de Avar\u00e9. Seis equipes participaram das disputas, sendo feitas pelo sistema de eliminat\u00f3ria simples, comRead More...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"ANGLO AVAR\u00c9\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-17T20:20:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-17T20:21:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FREA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FREA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/\"},\"author\":{\"name\":\"FREA\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#\\\/schema\\\/person\\\/e93891dc9c89020ea5a481646d06cd32\"},\"headline\":\"TORNEIO DE QUEIMADA DOS 5\u00bas ANOS\",\"datePublished\":\"2016-03-17T20:20:53+00:00\",\"dateModified\":\"2016-03-17T20:21:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/\"},\"wordCount\":82,\"image\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/Torneio_de_queimada_5_anos_2016_00001.jpg\",\"articleSection\":[\"2016\",\"Arquivo\",\"Esportes\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/\",\"name\":\"TORNEIO DE QUEIMADA DOS 5\u00bas ANOS - ANGLO AVAR\u00c9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/Torneio_de_queimada_5_anos_2016_00001.jpg\",\"datePublished\":\"2016-03-17T20:20:53+00:00\",\"dateModified\":\"2016-03-17T20:21:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#\\\/schema\\\/person\\\/e93891dc9c89020ea5a481646d06cd32\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/Torneio_de_queimada_5_anos_2016_00001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/Torneio_de_queimada_5_anos_2016_00001.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/torneio-de-queimada-dos-5os-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TORNEIO DE QUEIMADA DOS 5\u00bas ANOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/\",\"name\":\"ANGLO AVAR\u00c9\",\"description\":\"Para os melhores professores, o melhor conte\u00fado. No Anglo, tudo come\u00e7a na sala de aula.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#\\\/schema\\\/person\\\/e93891dc9c89020ea5a481646d06cd32\",\"name\":\"FREA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g\",\"caption\":\"FREA\"},\"description\":\"Departamento de Inform\u00e1tica na FUNDA\u00c7\u00c3O REGIONAL EDUCACIONAL DE AVAR\u00c9\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/author\\\/administrador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TORNEIO DE QUEIMADA DOS 5\u00bas ANOS - ANGLO AVAR\u00c9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"TORNEIO DE QUEIMADA DOS 5\u00bas ANOS - ANGLO AVAR\u00c9","og_description":"No dia 15 de mar\u00e7o foi realizado o Torneio de Queimada dos 5\u00bas Anos, do Col\u00e9gio Universit\u00e1rio de Avar\u00e9. Seis equipes participaram das disputas, sendo feitas pelo sistema de eliminat\u00f3ria simples, comRead More...","og_url":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/","og_site_name":"ANGLO AVAR\u00c9","article_published_time":"2016-03-17T20:20:53+00:00","article_modified_time":"2016-03-17T20:21:18+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001.jpg","type":"image\/jpeg"}],"author":"FREA","twitter_misc":{"Escrito por":"FREA"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/#article","isPartOf":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/"},"author":{"name":"FREA","@id":"https:\/\/www.colegioangloavare.com.br\/site\/#\/schema\/person\/e93891dc9c89020ea5a481646d06cd32"},"headline":"TORNEIO DE QUEIMADA DOS 5\u00bas ANOS","datePublished":"2016-03-17T20:20:53+00:00","dateModified":"2016-03-17T20:21:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/"},"wordCount":82,"image":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001.jpg","articleSection":["2016","Arquivo","Esportes"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/","url":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/","name":"TORNEIO DE QUEIMADA DOS 5\u00bas ANOS - ANGLO AVAR\u00c9","isPartOf":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/#primaryimage"},"image":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001.jpg","datePublished":"2016-03-17T20:20:53+00:00","dateModified":"2016-03-17T20:21:18+00:00","author":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/#\/schema\/person\/e93891dc9c89020ea5a481646d06cd32"},"breadcrumb":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/#primaryimage","url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001.jpg","contentUrl":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.colegioangloavare.com.br\/site\/torneio-de-queimada-dos-5os-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.colegioangloavare.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"TORNEIO DE QUEIMADA DOS 5\u00bas ANOS"}]},{"@type":"WebSite","@id":"https:\/\/www.colegioangloavare.com.br\/site\/#website","url":"https:\/\/www.colegioangloavare.com.br\/site\/","name":"ANGLO AVAR\u00c9","description":"Para os melhores professores, o melhor conte\u00fado. No Anglo, tudo come\u00e7a na sala de aula.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colegioangloavare.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.colegioangloavare.com.br\/site\/#\/schema\/person\/e93891dc9c89020ea5a481646d06cd32","name":"FREA","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g","caption":"FREA"},"description":"Departamento de Inform\u00e1tica na FUNDA\u00c7\u00c3O REGIONAL EDUCACIONAL DE AVAR\u00c9","url":"https:\/\/www.colegioangloavare.com.br\/site\/author\/administrador\/"}]}},"jetpack_featured_media_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2016\/03\/Torneio_de_queimada_5_anos_2016_00001.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts\/17270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/comments?post=17270"}],"version-history":[{"count":1,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts\/17270\/revisions"}],"predecessor-version":[{"id":17272,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts\/17270\/revisions\/17272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/media\/17271"}],"wp:attachment":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/media?parent=17270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/categories?post=17270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/tags?post=17270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}