{"id":35493,"date":"2024-09-07T09:59:28","date_gmt":"2024-09-07T12:59:28","guid":{"rendered":"https:\/\/www.colegioangloavare.com.br\/site\/?p=35493"},"modified":"2024-11-25T21:07:46","modified_gmt":"2024-11-26T00:07:46","slug":"coral-maos-que-cantam-na-festa-da-primavera","status":"publish","type":"post","link":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/","title":{"rendered":"Coral M\u00e3os que Cantam na Festa da Primavera"},"content":{"rendered":"<p>Coral M\u00e3os que Cantam na Festa da Primavera<\/p>\n<p><a href=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-35494\" src=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5.jpg\" alt=\"\" width=\"960\" height=\"960\" srcset=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5.jpg 960w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5-300x300.jpg 300w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5-150x150.jpg 150w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5-768x768.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a> <a href=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-3.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-35498\" src=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-3.jpg\" alt=\"\" width=\"720\" height=\"720\" srcset=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-3.jpg 720w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-3-300x300.jpg 300w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-3-150x150.jpg 150w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a> <a href=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-4.jpg\"><img decoding=\"async\" class=\"alignnone size-large wp-image-35499\" src=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-4-1024x1024.jpg\" alt=\"\" width=\"604\" height=\"604\" srcset=\"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-4-1024x1024.jpg 1024w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-4-300x300.jpg 300w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-4-150x150.jpg 150w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-4-768x768.jpg 768w, https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-4.jpg 1080w\" sizes=\"(max-width: 604px) 100vw, 604px\" \/><\/a><\/p>\n<div style=\"width: 478px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-35493-1\" width=\"478\" height=\"478\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-7.mp4?_=1\" \/><a href=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-7.mp4\">http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-7.mp4<\/a><\/video><\/div>\n<div style=\"width: 478px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-35493-2\" width=\"478\" height=\"478\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-1.mp4?_=2\" \/><a href=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-1.mp4\">http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-1.mp4<\/a><\/video><\/div>\n<div style=\"width: 478px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-35493-3\" width=\"478\" height=\"478\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-2.mp4?_=3\" \/><a href=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-2.mp4\">http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-2.mp4<\/a><\/video><\/div>\n<p>7<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coral M\u00e3os que Cantam na Festa da Primavera 7 &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":35494,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[84,3],"tags":[],"class_list":["post-35493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-84","category-arquivo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coral M\u00e3os que Cantam na Festa da Primavera - ANGLO AVAR\u00c9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coral M\u00e3os que Cantam na Festa da Primavera - ANGLO AVAR\u00c9\" \/>\n<meta property=\"og:description\" content=\"Coral M\u00e3os que Cantam na Festa da Primavera 7 &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/\" \/>\n<meta property=\"og:site_name\" content=\"ANGLO AVAR\u00c9\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-07T12:59:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-26T00:07:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FREA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FREA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/\"},\"author\":{\"name\":\"FREA\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#\\\/schema\\\/person\\\/e93891dc9c89020ea5a481646d06cd32\"},\"headline\":\"Coral M\u00e3os que Cantam na Festa da Primavera\",\"datePublished\":\"2024-09-07T12:59:28+00:00\",\"dateModified\":\"2024-11-26T00:07:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/\"},\"wordCount\":67,\"image\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/coral-maos-que-cantam-anglo-2024-5.jpg\",\"articleSection\":[\"2024\",\"Arquivo\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/\",\"name\":\"Coral M\u00e3os que Cantam na Festa da Primavera - ANGLO AVAR\u00c9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/coral-maos-que-cantam-anglo-2024-5.jpg\",\"datePublished\":\"2024-09-07T12:59:28+00:00\",\"dateModified\":\"2024-11-26T00:07:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#\\\/schema\\\/person\\\/e93891dc9c89020ea5a481646d06cd32\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/coral-maos-que-cantam-anglo-2024-5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/coral-maos-que-cantam-anglo-2024-5.jpg\",\"width\":960,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/coral-maos-que-cantam-na-festa-da-primavera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coral M\u00e3os que Cantam na Festa da Primavera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/\",\"name\":\"ANGLO AVAR\u00c9\",\"description\":\"Para os melhores professores, o melhor conte\u00fado. No Anglo, tudo come\u00e7a na sala de aula.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/#\\\/schema\\\/person\\\/e93891dc9c89020ea5a481646d06cd32\",\"name\":\"FREA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g\",\"caption\":\"FREA\"},\"description\":\"Departamento de Inform\u00e1tica na FUNDA\u00c7\u00c3O REGIONAL EDUCACIONAL DE AVAR\u00c9\",\"url\":\"https:\\\/\\\/www.colegioangloavare.com.br\\\/site\\\/author\\\/administrador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coral M\u00e3os que Cantam na Festa da Primavera - ANGLO AVAR\u00c9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/","og_locale":"pt_BR","og_type":"article","og_title":"Coral M\u00e3os que Cantam na Festa da Primavera - ANGLO AVAR\u00c9","og_description":"Coral M\u00e3os que Cantam na Festa da Primavera 7 &nbsp;","og_url":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/","og_site_name":"ANGLO AVAR\u00c9","article_published_time":"2024-09-07T12:59:28+00:00","article_modified_time":"2024-11-26T00:07:46+00:00","og_image":[{"width":960,"height":960,"url":"http:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5.jpg","type":"image\/jpeg"}],"author":"FREA","twitter_misc":{"Escrito por":"FREA","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/#article","isPartOf":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/"},"author":{"name":"FREA","@id":"https:\/\/www.colegioangloavare.com.br\/site\/#\/schema\/person\/e93891dc9c89020ea5a481646d06cd32"},"headline":"Coral M\u00e3os que Cantam na Festa da Primavera","datePublished":"2024-09-07T12:59:28+00:00","dateModified":"2024-11-26T00:07:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/"},"wordCount":67,"image":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5.jpg","articleSection":["2024","Arquivo"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/","url":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/","name":"Coral M\u00e3os que Cantam na Festa da Primavera - ANGLO AVAR\u00c9","isPartOf":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/#primaryimage"},"image":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5.jpg","datePublished":"2024-09-07T12:59:28+00:00","dateModified":"2024-11-26T00:07:46+00:00","author":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/#\/schema\/person\/e93891dc9c89020ea5a481646d06cd32"},"breadcrumb":{"@id":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/#primaryimage","url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5.jpg","contentUrl":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5.jpg","width":960,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.colegioangloavare.com.br\/site\/coral-maos-que-cantam-na-festa-da-primavera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.colegioangloavare.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Coral M\u00e3os que Cantam na Festa da Primavera"}]},{"@type":"WebSite","@id":"https:\/\/www.colegioangloavare.com.br\/site\/#website","url":"https:\/\/www.colegioangloavare.com.br\/site\/","name":"ANGLO AVAR\u00c9","description":"Para os melhores professores, o melhor conte\u00fado. No Anglo, tudo come\u00e7a na sala de aula.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colegioangloavare.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.colegioangloavare.com.br\/site\/#\/schema\/person\/e93891dc9c89020ea5a481646d06cd32","name":"FREA","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1617b9d57cce2b8f36041f2af3f487cc283646e159b7bfb5fbc0717d39cd86a8?s=96&d=mm&r=g","caption":"FREA"},"description":"Departamento de Inform\u00e1tica na FUNDA\u00c7\u00c3O REGIONAL EDUCACIONAL DE AVAR\u00c9","url":"https:\/\/www.colegioangloavare.com.br\/site\/author\/administrador\/"}]}},"jetpack_featured_media_url":"https:\/\/www.colegioangloavare.com.br\/site\/wp-content\/uploads\/2024\/11\/coral-maos-que-cantam-anglo-2024-5.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts\/35493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/comments?post=35493"}],"version-history":[{"count":1,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts\/35493\/revisions"}],"predecessor-version":[{"id":35500,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/posts\/35493\/revisions\/35500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/media\/35494"}],"wp:attachment":[{"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/media?parent=35493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/categories?post=35493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.colegioangloavare.com.br\/site\/wp-json\/wp\/v2\/tags?post=35493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}